{"id":241,"date":"2024-08-30T15:51:20","date_gmt":"2024-08-30T13:51:20","guid":{"rendered":"https:\/\/yakasa.online\/lp\/?p=241"},"modified":"2024-08-30T15:51:20","modified_gmt":"2024-08-30T13:51:20","slug":"aviso-legal","status":"publish","type":"post","link":"https:\/\/yakasa.online\/lp\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">Aviso Legal<\/h2>\n\n\n\n<p><strong>Aviso Legal:<\/strong>&nbsp;LSSI En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI) se exponen los datos identificativos de la empresa.<\/p>\n\n\n\n<p><strong>Denominaci\u00f3n social:<\/strong>&nbsp;Metro 2 Real Estate SL<br><strong>CIF:<\/strong>&nbsp;B76781913<br><strong>Domicilio:&nbsp;<\/strong>Avda. Jos\u00e9 Miguel Galv\u00e1n Bello,<br>n\u00ba 38, Local 5, (C. P. 38612) El M\u00e9dano,<br>Granadilla de Abona, Santa Cruz de Tenerife<\/p>\n\n\n\n<p><strong>Sitio Web, uso y responsabilidades:<\/strong>&nbsp;En este sitio Web, METRO CUADRADO (&nbsp;Metro 2 Real Estate SL.) pone a su disposici\u00f3n toda la informaci\u00f3n necesaria para conocer la bolsa de inmuebles que comercializamos y las soluciones y servicios que ofrecemos a nuestros clientes.<\/p>\n\n\n\n<p>Los textos, im\u00e1genes y contenidos incluidos en este sitio Web son propiedad de METRO CUADRADO (&nbsp;Metro 2 Real Estate SL). Queda expresamente prohibida la reproducci\u00f3n, copia, comunicaci\u00f3n p\u00fablica, distribuci\u00f3n, manipulaci\u00f3n, y cualquier otra forma de utilizaci\u00f3n, de todo o parte de este sitio Web o de cualquiera de sus contenidos, sin la previa y expresa autorizaci\u00f3n por escrito de METRO CUADRADO (&nbsp;Metro 2 Real Estate SL).<\/p>\n\n\n\n<p>Usted no puede utilizar el servicio para fines il\u00edcitos.<\/p>\n\n\n\n<p>Es condici\u00f3n indispensable ser mayor de edad para hacer uso de los servicios de este sitio web.<\/p>\n\n\n\n<p>Este sitio Web puede contener enlaces a p\u00e1ginas externas sobre las cuales METRO CUADRADO (&nbsp;Metro 2 Real Estate SL.) no se responsabiliza ni de los contenidos ni de cualquier otro aspecto relacionado con dichos sitios Web.<\/p>\n\n\n\n<p>METRO CUADRADO (&nbsp;Metro 2 Real Estate SL.) puede modificar sin previo aviso las caracter\u00edsticas de sus productos y servicios, as\u00ed como cualquier otra informaci\u00f3n aqu\u00ed recogida.<\/p>\n\n\n\n<p><strong>Informaci\u00f3n Publicada:<\/strong>&nbsp;La informaci\u00f3n publicada es actualizada frecuentemente por lo que se aconseja visitar a menudo el sitio Web.<\/p>\n\n\n\n<p>METRO CUADRADO (&nbsp;Metro 2 Real Estate SL.) no garantiza la fiabilidad absoluta de las caracter\u00edsticas de los inmuebles publicados, ya que aunque siempre se verifique pueden producirse errores en los datos publicados.<\/p>\n\n\n\n<p>La informaci\u00f3n detallada (precios, caracter\u00edsticas\u2026) que aparecen en este sitio Web no constituyen una oferta contractual, y se publican a efectos meramente informativos.<\/p>\n\n\n\n<p>METRO CUADRADO (&nbsp;Metro 2 Real Estate SL.) no se responsabiliza de cualquier da\u00f1o directo o indirecto que pueda ocasionar la exactitud o veracidad de dicha informaci\u00f3n o el uso que de ella pueda hacerse.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aviso Legal Aviso Legal:&nbsp;LSSI En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI) se exponen los datos identificativos de la empresa. Denominaci\u00f3n social:&nbsp;Metro 2 Real Estate SLCIF:&nbsp;B76781913Domicilio:&nbsp;Avda. Jos\u00e9 Miguel Galv\u00e1n Bello,n\u00ba 38, Local 5, (C. P. 38612) El M\u00e9dano,Granadilla [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"full-width","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-241","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/posts\/241"}],"collection":[{"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":1,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/posts\/241\/revisions"}],"predecessor-version":[{"id":242,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/posts\/241\/revisions\/242"}],"wp:attachment":[{"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/media?parent=241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/categories?post=241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yakasa.online\/lp\/wp-json\/wp\/v2\/tags?post=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}